{"id":188,"date":"2021-02-18T17:00:00","date_gmt":"2021-02-18T22:00:00","guid":{"rendered":"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/?p=188"},"modified":"2023-11-18T22:32:57","modified_gmt":"2023-11-19T03:32:57","slug":"prendre-la-cle-des-champs-au-temps-de-la-covid-19","status":"publish","type":"post","link":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/2021\/02\/18\/prendre-la-cle-des-champs-au-temps-de-la-covid-19\/","title":{"rendered":"Prendre la cl\u00e9 des champs au temps de la Covid-19"},"content":{"rendered":"\n<p><strong>En les amplifiant de fa\u00e7on soudaine, la pand\u00e9mie de la COVID-19 a r\u00e9v\u00e9l\u00e9 au grand jour les in\u00e9galit\u00e9s socio-\u00e9conomiques de sant\u00e9 qui existent entre diff\u00e9rents secteurs de Montr\u00e9al. &nbsp;Le confinement a forc\u00e9 une grande partie de la population \u00e0 recentrer son existence sur les environs tr\u00e8s rapproch\u00e9s de son domicile et toutes et tous n\u2019ont pas eu acc\u00e8s \u00e0 un environnement \u00e9quivalent. Comment se manifestent les in\u00e9galit\u00e9s en regard de l\u2019acc\u00e8s \u00e0 la nature pour les montr\u00e9alaises et les montr\u00e9alais et quelles sont les pistes de solution pour les r\u00e9duire?<\/strong><\/p>\n\n\n\n<p><strong>Annie Lamalice<\/strong>, dipl\u00f4m\u00e9e 2020 du doctorat en g\u00e9ographie sous la co-supervision de Thora Herrmann de l&rsquo;Universit\u00e9 de Montr\u00e9al, ainsi que de Jean-Louis Martin et Sylvie Blangy de l&rsquo;Universit\u00e9 de Montpellier.<\/p>\n\n\n\n<p>Bien qu\u2019il ne soit pas le seul facteur \u00e0 consid\u00e9rer, notre environnement urbain a un impact sur notre sant\u00e9, comme en t\u00e9moigne l\u2019esp\u00e9rance de vie qui varie de plusieurs ann\u00e9es entre les quartiers montr\u00e9alais les plus ais\u00e9s et ceux o\u00f9 les indices de d\u00e9favorisation sont les plus alarmants. Cette diff\u00e9rence atteint presque 11 ans lorsque l\u2019on compare Hochelaga-Maisonneuve (74,2 ans) et Ville Saint-Laurent (85 ans)<sup>1<\/sup>. Certains facteurs de risque \u00e0 l\u2019origine de ces in\u00e9galit\u00e9s peuvent \u00eatre observ\u00e9s depuis le ciel. \u00c0 l\u2019\u00e9chelle de l\u2019\u00eele, les grands parcs et les ruelles vertes des quartiers centraux qui s\u2019\u00e9tendent sur les pourtours du Mont-Royal tranchent avec les raffineries de l\u2019est, les bords d\u2019autoroute et autres \u00eelots de chaleur urbains. \u00c0 une \u00e9chelle plus fine, le contraste net entre l\u2019\u00eelot de verdure tachet\u00e9 du bleu azur des piscines creus\u00e9es de Ville Mont-Royal et le gris de l\u2019asphalte et du bitume dominant du c\u00f4t\u00e9 de Parc-Extension sugg\u00e8re un acc\u00e8s in\u00e9gal aux espaces verts. Or, l\u2019acc\u00e8s \u00e0 des espaces verts de qualit\u00e9 permet de r\u00e9duire les in\u00e9galit\u00e9s socio-\u00e9conomiques en procurant des bienfaits pour la sant\u00e9 physique et mentale<sup>2,3<\/sup>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>En sant\u00e9 sous la canop\u00e9e<\/strong><\/h2>\n\n\n\n<p>En ville, les \u00eelots de chaleurs \u2013 espaces caract\u00e9ris\u00e9s par une absence de v\u00e9g\u00e9tation \u2013 contribuent \u00e0 accro\u00eetre la pollution de l\u2019air.&nbsp;Les arbres et les espaces verts am\u00e9liorent la qualit\u00e9 de l\u2019environnement en absorbant les polluants comme l\u2019ozone et les m\u00e9taux lourds, et en r\u00e9duisant le bruit et la temp\u00e9rature ambiante<sup>4<\/sup>. La cr\u00e9ation d\u2019\u00eelots de fra\u00eecheur permet ainsi de diminuer la temp\u00e9rature et d\u2019am\u00e9liorer la qualit\u00e9 de l\u2019air. L\u2019indice de canop\u00e9e, qui correspond \u00e0 la proportion de la superficie a\u00e9rienne occup\u00e9e par le feuillage des arbres, a une valeur moyenne de 20% sur l\u2019\u00eele de Montr\u00e9al. Les effets sont cependant optimaux sur la qualit\u00e9 de l\u2019air et pour le rafra\u00eechissement des temp\u00e9ratures lorsque la canop\u00e9e couvre au moins 40% de l\u2019espace urbain<sup>5<\/sup>.<\/p>\n\n\n\n<p>Contrer les effets nocifs des \u00eelots de chaleur sur la sant\u00e9 devient de plus en plus pr\u00e9occupant dans le contexte des changements climatiques et de la multiplication des \u00e9pisodes de canicule.&nbsp;La pr\u00e9sence de milieux naturels et la fr\u00e9quentation des espaces verts procurent plusieurs bienfaits pour la sant\u00e9, notamment une r\u00e9duction de l&rsquo;incidence des accidents vasculaires c\u00e9r\u00e9braux, de l&rsquo;hypertension, de l&rsquo;asthme et des maladies coronariennes<sup>6<\/sup>. Une m\u00e9ta-analyse r\u00e9cente a m\u00eame permis d\u2019\u00e9tablir une association inverse entre l&rsquo;exposition \u00e0 la verdure environnante et la mortalit\u00e9, toutes causes confondues<sup>7<\/sup>. De nombreuses \u00e9tudes ont \u00e9galement d\u00e9montr\u00e9 les bienfaits du contact avec la nature sur la r\u00e9duction du stress et de la fatigue et, en contexte urbain, sur l\u2019augmentation de la coh\u00e9sion sociale et la r\u00e9duction de l\u2019isolement social<sup>8<\/sup>.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"454\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-1-2.jpg\" alt=\"\" class=\"wp-image-268\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-1-2.jpg 711w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-1-2-300x192.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-1-2-450x287.jpg 450w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"465\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-2-2.jpg\" alt=\"\" class=\"wp-image-270\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-2-2.jpg 722w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-2-2-300x193.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-2-2-450x290.jpg 450w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Certaines citadines et certains citadins vivent tout pr\u00e8s de l\u2019autoroute m\u00e9tropolitaine, \u00eelot de chaleur par excellence \u00e0 Montr\u00e9al.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des populations captives du bitume<\/strong><\/h2>\n\n\n\n<p>Pour changer d\u2019air sans quitter l\u2019\u00eele, les montr\u00e9alaises et les montr\u00e9alais ont \u00e9t\u00e9 plus nombreuses et nombreux que jamais \u00e0 se pr\u00eater \u00e0 l\u2019art du jardinage. Toutefois, toutes et tous ne b\u00e9n\u00e9ficient malheureusement pas d\u2019un espace suffisant. Alors m\u00eame qu\u2019une crise du logement frappe Montr\u00e9al et que les citoyennes et les citoyens doivent consacrer une part de plus en plus importante de leur revenu pour payer un logement de plus en plus \u00e9troit, la crise sanitaire est venue renforcer dramatiquement le manque d\u2019espace subi par plusieurs. Les effets cumul\u00e9s de la crise sanitaire et de la crise du logement ont pour effet d\u2019amplifier l\u2019isolement de certaines populations, d\u2019autant plus que les enjeux li\u00e9s \u00e0 la mobilit\u00e9 se sont \u00e9galement accentu\u00e9s en ville avec la peur de contracter le virus dans les transports collectifs. La pr\u00e9sence d\u2019espaces verts \u00e0 proximit\u00e9 du lieu de r\u00e9sidence est particuli\u00e8rement importante pour les enfants et les personnes \u00e0 faible revenu, car ces populations sont davantage captives de leurs quartiers<sup>9,10<\/sup>.<\/p>\n\n\n\n<p>Si l\u2019ensemble des familles montr\u00e9alaises vit \u00e0 moins de 800 m\u00e8tres d\u2019un parc dot\u00e9 d\u2019installations sportives, la quantit\u00e9 et la qualit\u00e9 des espaces verts tendent \u00e0 \u00eatre largement moindres dans les secteurs \u00e9conomiquement d\u00e9favoris\u00e9s. Une \u00e9tude sur l\u2019accessibilit\u00e9 des parcs dans huit arrondissements montr\u00e9alais a d\u00e9montr\u00e9 qu\u2019une famille ais\u00e9e peut compter sur plus du double de superficie d\u2019espace vert qu\u2019une famille moins nantie<sup>11<\/sup>. Cet \u00e9cart peut d\u2019ailleurs continuer \u00e0 se creuser si de grands efforts ne sont pas faits pour inverser la tendance. De fait, dans les quartiers plus ais\u00e9s la cr\u00e9ation de nouveaux espaces verts a suivi son cours m\u00eame en temps de pand\u00e9mie, comme c&rsquo;est le cas pour les 10 nouvelles ruelles vertes et tron\u00e7ons champ\u00eatres fra\u00eechement inaugur\u00e9s dans l\u2019arrondissement du Plateau Mont-Royal. Ce portrait contraste avec celui des arrondissements les plus touch\u00e9s par la pand\u00e9mie. Ceux-ci se rel\u00e8vent en effet avec plus de difficult\u00e9. Au plus fort de la crise en avril et mai 2020, l\u2019arrondissement de Montr\u00e9al-Nord \u00e9tait celui qui comptait le plus de cas d\u2019infection par tranche de 100&nbsp;000 habitants, notamment parce que les travailleuses essentielles et les travailleurs essentiels les moins bien r\u00e9mun\u00e9r\u00e9s du secteur de la sant\u00e9 sont surrepr\u00e9sent\u00e9s au sein de cette population<sup>12<\/sup>. \u00c0 Montr\u00e9al-Nord, il y a environ 5000 m<sup>2<\/sup> de parcs municipaux par tranche de 1000 habitants. C\u2019est presque cinq fois moins que la moyenne montr\u00e9alaise de 24&nbsp;000 m<sup>2<\/sup> par tranche de 1000 habitants<sup>13<\/sup>. Celles-l\u00e0 et ceux-l\u00e0 m\u00eames qui prennent soin des citadines et des citadins ont ainsi un acc\u00e8s plus restreint aux am\u00e9nagements urbains procurant du bien-\u00eatre.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"444\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-3-1.jpg\" alt=\"\" class=\"wp-image-197\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-3-1.jpg 657w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-3-1-300x203.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-3-1-450x304.jpg 450w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"432\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-4-2.jpg\" alt=\"\" class=\"wp-image-271\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-4-2.jpg 657w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-4-2-300x197.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-4-2-450x296.jpg 450w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Certaines montr\u00e9alaises et certains montr\u00e9alais b\u00e9n\u00e9ficient d\u2019am\u00e9nagements champ\u00eatres en plein c\u0153ur de la m\u00e9tropole<\/p>\n\n\n\n<p>Certaines privil\u00e9gi\u00e9es et certains privil\u00e9gi\u00e9s ont pu fuir l\u2019\u00e9picentre de la pand\u00e9mie en se r\u00e9fugiant dans leurs r\u00e9sidences secondaires et ont ainsi pu profiter de la p\u00e9riode de confinement pour se ressourcer et se reconnecter \u00e0 la nature. Pour prendre la cl\u00e9 des champs, d\u2019autres ont patiemment attendu la r\u00e9ouverture des campings et autres lieux de vill\u00e9giature afin d\u2019assouvir leur soif de plein air et troquer les quatre murs de leur logis pour le calme apaisant des grands espaces. Toutes et tous ne peuvent cependant se permettre de mettre leur quotidien sur pause le temps d\u2019un s\u00e9jour \u00e0 l\u2019ext\u00e9rieur de la ville. Pour cela, il faut des vacances, un moyen de locomotion et de l\u2019\u00e9quipement qui est loin d\u2019\u00eatre \u00e0 la port\u00e9e de toutes les bourses. La pand\u00e9mie a mis le transport interurbain sur pause et surcharg\u00e9 les services d\u2019autopartage.<\/p>\n\n\n\n<p>On peut bien se rendre jusqu\u2019au point d\u2019eau, \u00e7a ne signifie pas qu\u2019on puisse s\u2019y abreuver. La chercheure Annie Poulin et le chercheur Fran\u00e7ois Brissette de l\u2019\u00c9TS, sp\u00e9cialistes de l\u2019hydrologie et des changements climatiques, soulignent que bien que les plans d\u2019eau soient abondants et th\u00e9oriquement publics, leur acc\u00e8s y est de plus en plus restreint chaque ann\u00e9e, en particulier dans le sud du Qu\u00e9bec<sup>14<\/sup>. Cela s\u2019explique par la privatisation accrue des terrains autour des lacs et le manque de volont\u00e9 politique, notamment parce que les municipalit\u00e9s captent une partie importante de leur financement \u00e0 travers les taxes des riverains. Sur l\u2019\u00eele de Montr\u00e9al, l\u2019acc\u00e8s aux berges du fleuve Saint-Laurent et de la rivi\u00e8re des Prairies est in\u00e9gal. Les berges sont tant\u00f4t am\u00e9nag\u00e9es pour le grand public, tant\u00f4t accapar\u00e9es par des maisons cossues, une autoroute ou encore l\u2019industrie.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"433\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-5.jpg\" alt=\"\" class=\"wp-image-193\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-5.jpg 684w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-5-300x190.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-5-450x285.jpg 450w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"444\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-6-1.jpg\" alt=\"\" class=\"wp-image-272\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-6-1.jpg 664w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-6-1-300x201.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-6-1-450x301.jpg 450w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Les plans d\u2019eau sont de moins en moins accessibles pour les qu\u00e9b\u00e9coises et les qu\u00e9b\u00e9cois qui ne sont pas propri\u00e9taires riverains.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La nature pour toutes et tous<\/strong><\/h2>\n\n\n\n<p>Parce que mettre le quotidien sur pause et b\u00e9n\u00e9ficier des bienfaits de la nature ne devrait \u00eatre un luxe pour personne, il s\u2019impose de consid\u00e9rer quelques pistes de r\u00e9flexion et d\u2019action pour que toutes et tous puissent acc\u00e9der \u00e0 la verdure, aux berges et aux activit\u00e9s de plein air, en ville ou hors de celle-ci. Face \u00e0 l\u2019insuffisance des espaces verts qu\u2019elle constate \u00e0 Montr\u00e9al, la professeure d\u2019\u00e9cologie urbaine \u00e0 l\u2019Universit\u00e9 de Concordia, Carly Ziter, propose de saisir l\u2019apr\u00e8s-pand\u00e9mie comme une \u00ab&nbsp;occasion unique pour plaider en faveur de villes plus vertes, et plus \u00e9quitables&nbsp;\u00bb<sup>15<\/sup>. Elle invite \u00e0 repenser compl\u00e8tement les quartiers pour les personnes qui y vivent plut\u00f4t que pour les voitures qui y transitent.&nbsp; Pour agir en ce sens, le guide <a href=\"https:\/\/souslespaves.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Sous les pav\u00e9s<\/em><\/a><em> <\/em>d\u00e9velopp\u00e9 par le Centre d\u2019\u00e9cologie urbaine de Montr\u00e9al propose une d\u00e9marche de d\u00e9pavage participatif qui vise \u00e0 r\u00e9duire les surfaces min\u00e9ralis\u00e9es en mobilisant les citoyennes et les citoyens autour des enjeux d\u2019adaptation aux changements climatiques.<\/p>\n\n\n\n<p>La p\u00e9dagogie en plein air est une piste prometteuse pour faciliter le respect des r\u00e8gles de distanciation physique tout en maximisant les bienfaits du contact avec la nature pour la sant\u00e9. Le professeur \u00e0 la facult\u00e9 d\u2019\u00e9ducation de l\u2019Universit\u00e9 de Sherbrooke Louis-Philippe Ayotte-Beaudet fait la promotion de ce projet p\u00e9dagogique, qui prend de l\u2019ampleur depuis plusieurs ann\u00e9es au Qu\u00e9bec et permet d\u2019ancrer les apprentissages et le d\u00e9veloppement des jeunes dans la nature, d\u00e8s la petite enfance. Parmi les avantages associ\u00e9s \u00e0 la p\u00e9dagogie en plein air, notons l\u2019am\u00e9lioration de l\u2019estime de soi et de la motivation des enfants, l\u2019am\u00e9lioration de la forme physique et le d\u00e9veloppement d\u2019un go\u00fbt pour le temps pass\u00e9 \u00e0 l\u2019ext\u00e9rieur, que les jeunes tendent \u00e0 transmettre \u00e0 leur entourage<sup>16,17<\/sup>. Julie Moffet, de la Fondation Monique-Fitzback, identifie <a href=\"https:\/\/centdegres.ca\/magazine\/sante-et-societe\/classes-exterieures-pedagogie-plein-air-10-idees-projets-rentree\/\" target=\"_blank\" rel=\"noreferrer noopener\">10 pistes d\u2019action pour mettre en place la p\u00e9dagogie en plein air<\/a> \u00e0 l\u2019\u00e9cole, de fa\u00e7on accessible et tout au long de l\u2019ann\u00e9e. Composer avec les conditions m\u00e9t\u00e9orologiques hivernales est certainement un d\u00e9fi de taille pour un projet \u00e9ducatif en plein air. Olivier Legault, cofondateur du Laboratoire de l\u2019hiver, encourage les citadines et les citadins \u00e0 am\u00e9liorer leur rapport \u00e0 la saison froide. Pour ce faire, il propose une <a href=\"https:\/\/www.lapresse.ca\/debats\/opinions\/2020-09-07\/l-hiver-s-en-vient.php\" target=\"_blank\" rel=\"noreferrer noopener\">strat\u00e9gie simple et efficace<\/a> soutenue par l\u2019action citoyenne et misant notamment sur des am\u00e9nagements urbains de proximit\u00e9 faciles \u00e0 mettre en place, tels que de petites buttes de neige qui peuvent \u00eatre utilis\u00e9es pour la glissade<sup>18<\/sup> .<\/p>\n\n\n\n<p>Pour pallier la perte d\u2019acc\u00e8s aux plans d\u2019eau qu\u2019ils observent au Qu\u00e9bec, la chercheure Annie Poulin et le chercheur Fran\u00e7ois Brissette de l\u2019\u00c9TS proposent d\u2019int\u00e9grer des acc\u00e8s riverains publics \u00e0 tous projets d\u2019infrastructures, ce qui implique de troquer quelques privil\u00e8ges individuels pour le bien commun<sup>19<\/sup>.&nbsp; Diff\u00e9rentes occasions de d\u00e9privatiser les berges afin d\u2019ouvrir de nouveaux acc\u00e8s au grand public peuvent \u00eatre saisies. C\u2019est ce qu\u2019a fait la ville de Montr\u00e9al en juillet 2020, en <a href=\"https:\/\/ici.radio-canada.ca\/nouvelle\/1720668\/patrimoine-anciennes-maisons-montreal-restauration\" target=\"_blank\" rel=\"noreferrer noopener\">achetant trois maisons patrimoniales<\/a> dans l\u2019ouest de l\u2019\u00eele pour assurer leur restauration et ainsi offrir \u00e0 la population de nouvelles fen\u00eatres sur la rivi\u00e8re des Prairies ainsi qu\u2019au futur Grand parc de l\u2019Ouest. La pr\u00e9sence d\u2019espaces verts et la cr\u00e9ation de nouvelles ouvertures sur les rives ne suffisent cependant pas \u00e0 optimiser les bienfaits sur la sant\u00e9 humaine. Encore faut-il que ces espaces soient accessibles et que toutes et tous s\u2019y sentent bienvenu.es. Pour celles et ceux qui n\u2019ont pas grandi en pratiquant le camping, le canot ou encore le ski de fond, les activit\u00e9s de plein air peuvent para\u00eetre inaccessibles. Pour contrer cette situation, des clubs de plein air interculturel proposent d\u2019initier les personnes de toutes origines au camping et \u00e0 de nombreuses activit\u00e9s telles que le ski de fond et le canot \u00ab&nbsp;m\u00eame s\u2019ils n\u2019ont pas de voiture, de mat\u00e9riel sp\u00e9cialis\u00e9, d\u2019exp\u00e9rience pr\u00e9alable ni un grand budget&nbsp;\u00bb<sup>20<\/sup>.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"688\" height=\"430\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-7.jpg\" alt=\"\" class=\"wp-image-195\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-7.jpg 688w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-7-300x188.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-7-450x281.jpg 450w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"433\" src=\"https:\/\/geoweb.lemig.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-8-1.jpg\" alt=\"\" class=\"wp-image-273\" srcset=\"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-8-1.jpg 684w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-8-1-300x190.jpg 300w, https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/wp-content\/uploads\/2021\/01\/Lamalice-8-1-450x285.jpg 450w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Une famille de quatre doit d\u00e9bourser $210 pour s\u00e9journer une nuit dans un chalet \u00ab&nbsp;\u00c9cho&nbsp;\u00bb de la SEPAQ. Le camping est moins dispendieux, mais requiert \u00e9quipement et savoir-faire.<\/p>\n\n\n\n<p>La crise sanitaire a r\u00e9v\u00e9l\u00e9 et amplifi\u00e9 une situation d\u2019injustice environnementale depuis longtemps subie par les montr\u00e9alaises et les montr\u00e9alais les moins nanti.es. La pr\u00e9sence et la qualit\u00e9 des espaces verts contribuent \u00e0 r\u00e9duire les in\u00e9galit\u00e9s socio-\u00e9conomiques en sant\u00e9, et cela a d\u2019autant plus d\u2019impact dans les milieux \u00e9conomiquement d\u00e9favoris\u00e9s. Accro\u00eetre la pr\u00e9sence et la qualit\u00e9 des espaces verts, en voil\u00e0 une bonne fa\u00e7on pour relancer l\u2019\u00e9conomie et mettre \u00e0 profit les c\u00f4nes orange et les <em>p\u00e9pines<\/em> de la ville de Montr\u00e9al!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>R\u00e9f\u00e9rences<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\"><li> Crespin, R. (2017). Villes et sant\u00e9. <em>Lien social et Politiques<\/em>, <em>78<\/em>, 4\u201117.<\/li><li>  Mitchell, R., &amp; Popham, F. (2008). Effect of exposure to natural environment on health inequalities\u202f: An observational population study. <em>The lancet<\/em>, <em>372<\/em>(9650), 1655\u20111660.<\/li><li>  Vida, S. (2011). <em>Les espaces verts urbains et la sant\u00e9\u2014Biblioth\u00e8que \u00c9lectronique en Loisir<\/em>. Direction de la sant\u00e9 environnementale et de la toxicologie, Institut national de sant\u00e9 publique du Qu\u00e9bec, D\u00e9partement de psychiatrie, Centre universitaire de sant\u00e9 McGill, Universit\u00e9 Mcgil. http:\/\/bel.uqtr.ca\/id\/eprint\/3155\/<\/li><li> Vida, S. (2011). <em>Op. Cit.<\/em><\/li><li>Ziter, C. D., Pedersen, E. J., Kucharik, C. J., &amp; Turner, M. G. (2019). Scale-dependent interactions between tree canopy cover and impervious surfaces reduce daytime urban heat during summer. <em>Proceedings of the National Academy of Sciences<\/em>, <em>116<\/em>(15), 7575\u20117580. https:\/\/doi.org\/10.1073\/pnas.1817561116<\/li><li>Twohig-Bennett, C., &amp; Jones, A. (2018). The health benefits of the great outdoors: A systematic review and meta-analysis of greenspace exposure and health outcomes. <em>Environmental Research<\/em>, <em>166<\/em>, 628\u2011637. https:\/\/doi.org\/10.1016\/j.envres.2018.06.030<\/li><li>Rojas-Rueda, D., Nieuwenhuijsen, M. J., Gascon, M., Perez-Leon, D., &amp; Mudu, P. (2019). Green spaces and mortality: A systematic review and meta-analysis of cohort studies. <em>The Lancet Planetary Health<\/em>, <em>3<\/em>(11), e469\u2011e477. https:\/\/doi.org\/10.1016\/S2542-5196(19)30215-3<\/li><li>Wood, L., Hooper, P., Foster, S., &amp; Bull, F. (2017). Public green spaces and positive mental health\u2013investigating the relationship between access, quantity and types of parks and mental wellbeing. <em>Health &amp; place<\/em>, <em>48<\/em>, 63\u201171.<\/li><li>Le Blanc, M.-F., Raynault, M.-F., &amp; Lessard, R. (2011). <em>Rapport du directeur de sant\u00e9 publique 2011. Les in\u00e9galit\u00e9s sociales de sant\u00e9 \u00e0 Montr\u00e9al, le chemin parcouru.<\/em><\/li><li>Maas, J., Verheij, R. A., Groenewegen, P. P., De Vries, S., &amp; Spreeuwenberg, P. (2006). Green space, urbanity, and health: How strong is the relation? <em>Journal of Epidemiology &amp; Community Health<\/em>, <em>60<\/em>(7), 587\u2011592.<\/li><li>B\u00e9dard, J., &amp; Jacques, M. (2010). <em>L\u2019accessibilit\u00e9 aux parcs et aux installations sportives pour les familles montr\u00e9alaises<\/em> (p. 50). Agence de la sant\u00e9 et des services sociaux de Montr\u00e9al.<\/li><li>L\u00e9vesque, K., Chouinard, T., &amp; Louis-Samuel, P. (2020, avril 28). <em>Montr\u00e9al-Nord, Saint-Michel et Rivi\u00e8re-des-Prairies en t\u00eate<\/em>. La Presse. https:\/\/www.lapresse.ca\/covid-19\/2020-04-28\/montreal-nord-saint-michel-et-riviere-des-prairies-en-tete<\/li><li>Collard, N. (2020, mai 9). <em>On s\u2019en va au parc?<\/em> La Presse. https:\/\/www.lapresse.ca\/societe\/2020-05-09\/on-s-en-va-au-parc<\/li><li>Poulin, A., &amp; Brissette, F. (2020). Les Qu\u00e9b\u00e9cois ont de moins en moins acc\u00e8s \u00e0 leurs plans d\u2019eau. Voici quoi faire pour que \u00e7a change. La Conversation. <a href=\"http:\/\/theconversation.com\/les-quebecois-ont-de-moins-en-moins-acces-a-leurs-plans-deau-voici-quoi-faire-pour-que-ca-change-143494\">http:\/\/theconversation.com\/les-quebecois-ont-de-moins-en-moins-acces-a-leurs-plans-deau-voici-quoi-faire-pour-que-ca-change-143494<\/a><\/li><li>Ziter, C. (2020). <em>L\u2019apr\u00e8s-COVID-19\u202f: Une transition vers des villes plus vertes<\/em>. La Presse. https:\/\/www.lapresse.ca\/debats\/opinions\/2020-05-06\/l-apres-covid-19-une-transition-vers-des-villes-plus-vertes<\/li><li>Cardinal, M.-J. (2020, ao\u00fbt 4). <em>Les petits miracles de la p\u00e9dagogie en plein air pour les enfants \u00e0 besoins particuliers<\/em>. 100\u00b0. https:\/\/centdegres.ca\/magazine\/sante-et-societe\/miracles-pedagogie-plein-air-enfants-besoins-particuliers\/<\/li><li>Polevoy, T. (2017, novembre 20). <em>\u00c9ducation en plein air\u202f: 3 enseignants font la preuve que m\u00eame en ville, c\u2019est possible!<\/em> 100\u00b0. https:\/\/centdegres.ca\/magazine\/sante-et-societe\/education-plein-air-4-enseignants-preuve-meme-ville-cest-possible\/<\/li><li>Legault, O. (2020). <em>L\u2019hiver s\u2019en vient<\/em>. La Presse. https:\/\/www.lapresse.ca\/debats\/opinions\/2020-09-07\/l-hiver-s-en-vient.php<\/li><li>Poulin, A., &amp; Brissette, F. (2020). Les Qu\u00e9b\u00e9cois ont de moins en moins acc\u00e8s \u00e0 leurs plans d\u2019eau. Voici quoi faire pour que \u00e7a change. La Conversation. <a href=\"http:\/\/theconversation.com\/les-quebecois-ont-de-moins-en-moins-acces-a-leurs-plans-deau-voici-quoi-faire-pour-que-ca-change-143494\">http:\/\/theconversation.com\/les-quebecois-ont-de-moins-en-moins-acces-a-leurs-plans-deau-voici-quoi-faire-pour-que-ca-change-143494<\/a><\/li><li>Programme Plein air Interculturel. (s.&nbsp;d.). <em>\u00c0 propos de nous | Plein air interculturel<\/em>. Consult\u00e9 9 ao\u00fbt 2020, \u00e0 l\u2019adresse https:\/\/www.pleinairinterculturel.com\/a-propos-de-nous\/<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>En les amplifiant de fa\u00e7on soudaine, la pand\u00e9mie de la COVID-19 a r\u00e9v\u00e9l\u00e9 au grand jour les in\u00e9galit\u00e9s [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-188","post","type-post","status-publish","format-standard","hentry","category-1ere-edition"],"_links":{"self":[{"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/posts\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":11,"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/posts\/188\/revisions"}],"predecessor-version":[{"id":896,"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/posts\/188\/revisions\/896"}],"wp:attachment":[{"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/media?parent=188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/categories?post=188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/geoweb.cedvs.umontreal.ca\/geolibre\/index.php\/wp-json\/wp\/v2\/tags?post=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}